{"id":7269,"date":"2021-02-14T09:46:25","date_gmt":"2021-02-14T08:46:25","guid":{"rendered":"http:\/\/b.brutennet.com\/insegnante-tefl-tesl-descrizione-del-lavoro\/"},"modified":"2021-02-14T09:46:25","modified_gmt":"2021-02-14T08:46:25","slug":"insegnante-tefl-tesl-descrizione-del-lavoro","status":"publish","type":"post","link":"https:\/\/eniyimeslekler.com\/it\/insegnante-tefl-tesl-descrizione-del-lavoro\/","title":{"rendered":"Insegnante TEFL\/TESL descrizione del lavoro"},"content":{"rendered":"<p>TEFL \u00e8 un termine generico per insegnare l&#8217;inglese a studenti di qualsiasi et\u00e0 la cui prima lingua non \u00e8 l&#8217;inglese.  TESL si riferisce all&#8217;insegnamento agli studenti che useranno l&#8217;inglese invece della loro lingua madre dopo essersi trasferiti in un paese di lingua inglese.<\/p>\n<blockquote class=\"quote\">\n<p>Questo lavoro pu\u00f2 essere una buona opportunit\u00e0 per viaggiare, oppure puoi restare e insegnare a casa.\n<\/p>\n<\/blockquote>\n<p><strong>Cosa fa un insegnante di lingua inglese?<\/strong> Datori di lavoro |  Qualifiche e formazione |  Competenze chiave<\/p>\n<p>Le responsabilit\u00e0 tipiche del lavoro includono:<\/p>\n<ul>\n<li>Pianificazione, preparazione e consegna delle lezioni<\/li>\n<li>Preparazione di materiali didattici<\/li>\n<li>Aiutare gli alunni a migliorare le loro capacit\u00e0 di ascolto, conversazione, lettura e scrittura tramite sessioni individuali e di gruppo<\/li>\n<li>Controllo e valutazione del lavoro degli alunni<\/li>\n<li>Organizzazione e conduzione di corsi specialistici<\/li>\n<li>Partecipare a eventi sociali<\/li>\n<\/ul>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_67_1 ez-toc-wrap-right counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >Contenuti<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/eniyimeslekler.com\/it\/insegnante-tefl-tesl-descrizione-del-lavoro\/#Datori_di_lavoro_tipici\" title=\"Datori di lavoro tipici\">Datori di lavoro tipici<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/eniyimeslekler.com\/it\/insegnante-tefl-tesl-descrizione-del-lavoro\/#Qualifiche_e_formazione_richieste\" title=\"Qualifiche e formazione richieste\">Qualifiche e formazione richieste<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/eniyimeslekler.com\/it\/insegnante-tefl-tesl-descrizione-del-lavoro\/#Competenze_chiave_per_insegnanti_TEFLTESL\" title=\"Competenze chiave per insegnanti TEFL\/TESL\">Competenze chiave per insegnanti TEFL\/TESL<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Datori_di_lavoro_tipici\"><\/span>Datori di lavoro tipici<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Scuole private<\/li>\n<li>Scuole mantenute<\/li>\n<li>Istituti di istruzione superiore e superiore<\/li>\n<li>Centri di educazione comunitaria e per adulti<\/li>\n<li>Organizzazioni di volontariato<\/li>\n<\/ul>\n<p>Ci sono opportunit\u00e0 di lavoro sia nel Regno Unito che all&#8217;estero.  I lavori nel Regno Unito sono spesso basati nelle aree urbane e prevedono l&#8217;insegnamento a studenti la cui prima lingua non \u00e8 l&#8217;inglese.  Durante la stagione delle vacanze estive \u00e8 disponibile un lavoro per insegnare l&#8217;inglese agli studenti stranieri che visitano il Regno Unito.<\/p>\n<p>Le opportunit\u00e0 sono pubblicizzate dai servizi per il lavoro e dalle agenzie di reclutamento, sui giornali nazionali, nel Times Educational Supplement e nel Times Higher Education e in pubblicazioni specializzate come EL Gazette.<\/p>\n<p>Il British Council fornisce informazioni sulla formazione e le opportunit\u00e0 di insegnare in varie localit\u00e0 all&#8217;estero.  Il programma JET (Japan Exchange and Teaching) \u00e8 sostenuto dal governo giapponese e recluta laureati britannici per lavorare come assistenti insegnanti di lingue, insegnando l&#8217;inglese nelle scuole in Giappone.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Qualifiche_e_formazione_richieste\"><\/span>Qualifiche e formazione richieste<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Potrebbe essere possibile diventare un insegnante TEFL\/TESL senza una laurea, anche se i datori di lavoro in genere cercano laureati che hanno approvato le qualifiche TEFL.  Una laurea in lingua, linguistica, istruzione o inglese sar\u00e0 particolarmente utile nelle applicazioni.<\/p>\n<p>Ci sono due principali qualifiche TEFL riconosciute a livello internazionale: il Cambridge CELTA (Certificate in English Language Teaching to Adults) e il corso TESOL del Trinity College London, comunemente indicato come CertTESOL. <\/p>\n<p>Per insegnare in alcuni paesi \u00e8 necessario avere lo status di insegnante qualificato (QTS) oltre a una qualifica TEFL e spesso almeno due anni di esperienza in classe generale.  La pertinente esperienza lavorativa acquisita come tutor privato, assistente linguistico o tutor di una scuola di lingue estiva pu\u00f2 essere utile.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Competenze_chiave_per_insegnanti_TEFLTESL\"><\/span>Competenze chiave per insegnanti TEFL\/TESL<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>Ottime capacit\u00e0 linguistiche parlate e scritte, con inglese e lingue straniere<\/li>\n<li>Dizione chiara<\/li>\n<li>Pazienza<\/li>\n<li>Pensiero laterale<\/li>\n<li>Fiducia<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>TEFL \u00e8 un termine generico per insegnare l&#8217;inglese a studenti di qualsiasi et\u00e0 la cui prima lingua non \u00e8 l&#8217;inglese. TESL si riferisce all&#8217;insegnamento agli studenti che useranno l&#8217;inglese invece della loro lingua madre dopo essersi trasferiti in un paese di lingua inglese. Questo lavoro pu\u00f2 essere una buona opportunit\u00e0 per viaggiare, oppure puoi restare &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105],"tags":[],"class_list":["post-7269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-professioni"],"_links":{"self":[{"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/posts\/7269"}],"collection":[{"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/comments?post=7269"}],"version-history":[{"count":0,"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/posts\/7269\/revisions"}],"wp:attachment":[{"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/media?parent=7269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/categories?post=7269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/tags?post=7269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}