{"id":6976,"date":"2020-12-28T04:00:11","date_gmt":"2020-12-28T03:00:11","guid":{"rendered":"https:\/\/eniyimeslekler.com\/it\/cosa-fa-un-artista-commerciale-come-diventare\/"},"modified":"2020-12-28T04:00:11","modified_gmt":"2020-12-28T03:00:11","slug":"cosa-fa-un-artista-commerciale-come-diventare","status":"publish","type":"post","link":"https:\/\/eniyimeslekler.com\/it\/cosa-fa-un-artista-commerciale-come-diventare\/","title":{"rendered":"Cosa fa un artista commerciale?\n Come diventare?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_67_1 ez-toc-wrap-right counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >Contenuti<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/eniyimeslekler.com\/it\/cosa-fa-un-artista-commerciale-come-diventare\/#Cose_un_artista_commerciale\" title=\"Cos\u2019\u00e8 un artista commerciale?\">Cos\u2019\u00e8 un artista commerciale?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/eniyimeslekler.com\/it\/cosa-fa-un-artista-commerciale-come-diventare\/#Cosa_fa_un_artista_commerciale\" title=\"Cosa fa un artista commerciale?\">Cosa fa un artista commerciale?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/eniyimeslekler.com\/it\/cosa-fa-un-artista-commerciale-come-diventare\/#Sei_adatto_per_essere_un_artista_commerciale\" title=\"Sei adatto per essere un artista commerciale?\">Sei adatto per essere un artista commerciale?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/eniyimeslekler.com\/it\/cosa-fa-un-artista-commerciale-come-diventare\/#Come_il_posto_di_lavoro_di_un_artista_commerciale\" title=\"Com\u2019\u00e8 il posto di lavoro di un artista commerciale?\">Com\u2019\u00e8 il posto di lavoro di un artista commerciale?<\/a><\/li><\/ul><\/nav><\/div>\n<h2 id=\"commercial-artist\"><span class=\"ez-toc-section\" id=\"Cose_un_artista_commerciale\"><\/span>Cos\u2019\u00e8 un artista commerciale?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La pubblicit\u00e0 \u00e8 ovunque intorno a noi!  Lo vediamo ogni giorno sotto forma di pubblicit\u00e0, brochure, loghi, confezioni di prodotti, cartelloni pubblicitari, copertine di libri e altre opere d\u2019arte simili.<\/p>\n<p>Gli artisti commerciali sono le persone che progettano questo tipo di pubblicit\u00e0.  L\u2019arte commerciale, a volte indicata come arte pubblicitaria, viene utilizzata per informare, promuovere e vendere beni e servizi utilizzando immagini visive per comunicare un messaggio.<\/p>\n<h2 id=\"commercial-artist\"><span class=\"ez-toc-section\" id=\"Cosa_fa_un_artista_commerciale\"><\/span>Cosa fa un artista commerciale?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Gli artisti commerciali creano pubblicit\u00e0 e imballaggi di prodotti ben progettati e realizzati, con conseguente aumento delle vendite per una variet\u00e0 di settori. <\/p>\n<p>Spesso incontrano un cliente per avere un\u2019idea generale di un concetto di progetto e quindi elaborare i dettagli in modo indipendente.  Parte di questo processo consiste nell\u2019aiutare il cliente a determinare i progetti migliori in base al tipo di prodotto o pubblicit\u00e0 e alla base di clienti target.  Quindi creano diverse bozze fino a quando il prodotto finito viene accettato;  queste bozze sono disegnate a mano o assistite da computer. <\/p>\n<p>Gli artisti commerciali parlano con i loro clienti durante tutto il processo di progettazione per tenerli aggiornati con la direzione del progetto, rispondere a qualsiasi domanda e ricevere input.  Spesso creano diverse versioni di un progetto finito in modo che i clienti possano scegliere i loro preferiti.<\/p>\n<p>Progettazione di marketing<\/p>\n<p>Un artista commerciale nel marketing pu\u00f2 essere responsabile della progettazione di display, brochure, imballaggi, loghi e grafica ambientale.  Devono tenere conto sia delle ricerche di mercato riguardanti il \u200b\u200bpubblico di destinazione, sia delle esigenze del cliente. <\/p>\n<p>Ci\u00f2 potrebbe richiedere l\u2019incontro con il cliente e la comprensione delle sue idee di base prima di iniziare il processo di progettazione.  Sviluppano i disegni per il progetto disegnando a mano alcuni schizzi o utilizzando un programma di computer grafica.  Possono anche lavorare a fianco di un direttore artistico. <\/p>\n<p>Editoria e design della comunicazione<\/p>\n<p>Un artista commerciale nell\u2019editoria e nella comunicazione aiuta con il layout elettronico della pubblicazione e con la progettazione di pubblicit\u00e0 stampate o materiali di marketing.  Nella progettazione di testi pubblicitari, viene utilizzata una variet\u00e0 di grafici e colori che soddisfano le specifiche della pubblicazione.  Questi artisti sono comunemente coinvolti nel processo di stampa, aiutando a decidere i gradi di carta o la selezione dell\u2019inchiostro.<\/p>\n<p>Le agenzie pubblicitarie progettano anche una serie di annunci stampati per le pubblicazioni e gli artisti commerciali sono invitati a creare progetti pubblicitari vincenti.  Presenteranno l\u2019annuncio al cliente e al rappresentante dell\u2019annuncio e tutte le modifiche verranno apportate in quel momento.  Quando tutte le modifiche sono state apportate e approvate, l\u2019annuncio sar\u00e0 pronto per essere incluso in una pubblicazione cartacea.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Sei_adatto_per_essere_un_artista_commerciale\"><\/span>Sei adatto per essere un artista commerciale?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>            Gli artisti commerciali hanno personalit\u00e0 distinte.  Tendono ad essere individui artistici, il che significa che sono creativi, intuitivi, sensibili, articolati ed espressivi.  Sono destrutturati, originali, anticonformisti e innovativi.  Alcuni di loro sono anche investigativi, nel senso che sono intellettuali, introspettivi e curiosi.\n        <\/p>\n<p>            Suona come te?  Fai il nostro test di carriera gratuito per scoprire se l\u2019artista commerciale \u00e8 uno dei tuoi migliori match in carriera.\n        <\/p>\n<h2 id=\"commercial-artist\"><span class=\"ez-toc-section\" id=\"Come_il_posto_di_lavoro_di_un_artista_commerciale\"><\/span>Com\u2019\u00e8 il posto di lavoro di un artista commerciale?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Gli artisti commerciali lavorano nell\u2019editoria, nella trasmissione, nel cinema, nel design digitale, nella pubblicit\u00e0 e nel marketing.  Sono impiegati in una variet\u00e0 di luoghi, come agenzie pubblicitarie, gruppi di marketing, produttori, societ\u00e0, case editrici di riviste, giornali, studi televisivi e cinematografici, societ\u00e0 di consulenza in progettazione grafica e studi privati \u200b\u200bfreelance. <\/p>\n<p>Gli artisti commerciali in genere lavorano con altri designer ed esperti di pubblicit\u00e0, mentre gli artisti autonomi in genere gestiscono da soli tutti gli aspetti di un progetto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cos\u2019\u00e8 un artista commerciale? La pubblicit\u00e0 \u00e8 ovunque intorno a noi! Lo vediamo ogni giorno sotto forma di pubblicit\u00e0, brochure, loghi, confezioni di prodotti, cartelloni pubblicitari, copertine di libri e altre opere d\u2019arte simili. Gli artisti commerciali sono le persone che progettano questo tipo di pubblicit\u00e0. L\u2019arte commerciale, a volte indicata come arte pubblicitaria, viene &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[104],"tags":[],"class_list":["post-6976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-come-diventare"],"_links":{"self":[{"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/posts\/6976"}],"collection":[{"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/comments?post=6976"}],"version-history":[{"count":0,"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/posts\/6976\/revisions"}],"wp:attachment":[{"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/media?parent=6976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/categories?post=6976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eniyimeslekler.com\/it\/wp-json\/wp\/v2\/tags?post=6976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}